{"id":306728,"date":"2025-06-12T10:47:02","date_gmt":"2025-06-12T08:47:02","guid":{"rendered":"https:\/\/kingsbox.com\/blog\/?p=306728"},"modified":"2025-06-12T11:24:00","modified_gmt":"2025-06-12T09:24:00","slug":"scopri-le-nuove-pedane-kingsbox-svr-platforms-la-soluzione-per-ridurre-rumori-e-vibrazioni-durante-il-sollevamento-pesi","status":"publish","type":"post","link":"https:\/\/kingsbox.com\/blog\/come-scegliere\/scopri-le-nuove-pedane-kingsbox-svr-platforms-la-soluzione-per-ridurre-rumori-e-vibrazioni-durante-il-sollevamento-pesi\/","title":{"rendered":"Scopri le nuove pedane KingsBox SVR Platforms: la soluzione per ridurre rumori e vibrazioni durante il sollevamento pesi"},"content":{"rendered":"<p>Una delle sfide principali per molti gestori di palestre \u00e8 quella di trovare una soluzione efficace per il sollevamento pesi, soprattutto quando si tratta di ridurre rumori e vibrazioni durante gli allenamenti. \u00c8 proprio da questa esigenza concreta che nasce la nostra idea: una soluzione semplice ma ingegnosa, pensata per abbattere il rumore, proteggere il pavimento e migliorare l\u2019ambiente della palestra, senza compromessi sulla qualit\u00e0 dell\u2019allenamento.<\/p>\n<p><a href=\"https:\/\/kingsbox.com\/it-it\/product\/kingsbox-svr-standard-lifting-platform\">La piattaforma KingsBox SVR<\/a> \u00e8 stata progettata per permettere alle palestre di accogliere al meglio i propri clienti che sollevano pesi, senza compromettere il comfort degli altri utenti. Grazie al suo design studiato nei minimi dettagli, aiuta i proprietari a creare uno spazio ottimale, dove rumori e vibrazioni non rappresentano pi\u00f9 un problema durante l\u2019allenamento.<\/p>\n<p>Chiunque sia stato in palestra almeno una volta sa quanto possa essere fastidioso sentire i pesi sbattere rumorosamente a terra. Ed \u00e8 proprio per rispondere a questo tipo di disagio che \u00e8 nata la nostra piattaforma KingsBox SVR: una soluzione pensata per migliorare la qualit\u00e0 dell\u2019ambiente, rendendolo pi\u00f9 silenzioso e piacevole per tutti.<\/p>\n<p><iframe title=\"Game-Changing Weightlifting Platform That Kills Noise &amp; Vibration\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/6RPEsXCHaT8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>In questo blog, vi raccontiamo la visione che ci ha guidati nello sviluppo di questa straordinaria soluzione e in che modo la soluzione che proponiamo contribuisce concretamente a ridurre rumori e vibrazioni all\u2019interno della palestra.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_74 counter-hierarchy ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Indice dei contenuti<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a0407b9cb305\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a0407b9cb305\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/kingsbox.com\/blog\/come-scegliere\/scopri-le-nuove-pedane-kingsbox-svr-platforms-la-soluzione-per-ridurre-rumori-e-vibrazioni-durante-il-sollevamento-pesi\/#Come_abbiamo_sviluppato_la_piattaforma_KingsBox_SVR_per_il_sollevamento_pesi\" >Come abbiamo sviluppato la piattaforma KingsBox SVR per il sollevamento pesi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/kingsbox.com\/blog\/come-scegliere\/scopri-le-nuove-pedane-kingsbox-svr-platforms-la-soluzione-per-ridurre-rumori-e-vibrazioni-durante-il-sollevamento-pesi\/#Differenze_tra_le_piattaforme_KingsBox_SVR_e_SVR_Elite\" >Differenze tra le piattaforme KingsBox SVR e SVR Elite<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/kingsbox.com\/blog\/come-scegliere\/scopri-le-nuove-pedane-kingsbox-svr-platforms-la-soluzione-per-ridurre-rumori-e-vibrazioni-durante-il-sollevamento-pesi\/#Perche_una_palestra_ha_bisogno_di_una_pedana\" >Perch\u00e9 una palestra ha bisogno di una pedana?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/kingsbox.com\/blog\/come-scegliere\/scopri-le-nuove-pedane-kingsbox-svr-platforms-la-soluzione-per-ridurre-rumori-e-vibrazioni-durante-il-sollevamento-pesi\/#Quale_pedana_da_sollevamento_scegliere_per_la_tua_palestra\" >Quale pedana da sollevamento scegliere per la tua palestra?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/kingsbox.com\/blog\/come-scegliere\/scopri-le-nuove-pedane-kingsbox-svr-platforms-la-soluzione-per-ridurre-rumori-e-vibrazioni-durante-il-sollevamento-pesi\/#Pronto_a_rivoluzionare_lesperienza_di_sollevamento_nella_tua_palestra\" >Pronto a rivoluzionare l\u2019esperienza di sollevamento nella tua palestra?<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Come_abbiamo_sviluppato_la_piattaforma_KingsBox_SVR_per_il_sollevamento_pesi\"><\/span><strong>Come abbiamo sviluppato la piattaforma KingsBox SVR per il sollevamento pesi<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La maggior parte delle pedane da sollevamento, soprattutto quelle pi\u00f9 economiche, utilizza un solo strato di piastrelle gomato. La nostra piattaforma KingsBox SVR, invece, \u00e8 stata progettata con un approccio completamente diverso: prevede pi\u00f9 strati di materiali ammortizzanti \u2014 sono presneti due strati nella <a href=\"https:\/\/kingsbox.com\/it-it\/product\/kingsbox-svr-standard-lifting-platform\">versione SVR<\/a> e ben tre strati nella <a href=\"https:\/\/kingsbox.com\/it-it\/product\/kingsbox-svr-elite-lifting-platform\">SVR Elite<\/a>.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-306689 alignnone\" src=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/KingsBox-Elite-Weightlifting-Platform-800x450.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/KingsBox-Elite-Weightlifting-Platform-800x450.png 800w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/KingsBox-Elite-Weightlifting-Platform-768x432.png 768w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/KingsBox-Elite-Weightlifting-Platform.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>La nostra pedana a pi\u00f9 strati non solo protegge in modo efficace il pavimento della palestra, ma riduce in modo significativo rumori e vibrazioni. Il risultato? Gli altri utenti possono allenarsi pi\u00f9 tranquillamente, mentre chi solleva pesi pu\u00f2 concentrarsi al massimo senza sentirsi a disagio.<\/p>\n<h3><strong>Test approfonditi e selezione dei materiali<\/strong><\/h3>\n<p>Our research and development team tested over 80 different combinations of materials to find the perfect mix. Here\u2019s how we performed the whole testing phase:<\/p>\n<h4>1. <strong>Selezione mirata delle combinazioni ottimali<\/strong><\/h4>\n<p>Abbiamo ridotto le combinazioni da 80 a 45, concentrandoci su quelle che offrivano il miglior rimbalzo del bilanciere senza che affondi troppo. Questo procedimento \u00e8 stato fondamentale per realizzare una piattaforma realmente adatta per le esigenze rigorose del weightlifting, del powerlifting e del sollevamento olimpico.<\/p>\n<h4>2. <strong>Test scientifici per scegliere i materiali pi\u00f9 adatti<\/strong><\/h4>\n<p>Presso la Facolt\u00e0 di Ingegneria Meccanica dell\u2019Universit\u00e0 di Lubiana, abbiamo analizzato i grafici dello Shock Response Spectrum (SRS) per ciascuna combinazione di materiali. Questo ci ha permesso di identificare con precisione quali materiali assorbivano meglio le vibrazioni. L\u2019elevata accuratezza richiesta in questa fase ci ha consentito di progettare una piattaforma con il perfetto equilibrio tra ammortizzazione e solidit\u00e0 \u2014 un aspetto fondamentale per il powerlifting e il sollevamento olimpico.<\/p>\n<h4>3.\u00a0 <strong>Test di durabilit\u00e0 in laboratorio e sul campo<\/strong><\/h4>\n<p>Dopo aver individuato la combinazione pi\u00f9 promettente, abbiamo effettuato test di resistenza sia in laboratorio che sul campo, in collaborazione con un affermato atleta europeo di cross-training. Le prove hanno simulato le condizioni ad alto impatto tipiche del weightlifting e del powerlifting. Alla fine la combinazione numero 39 ha superato ogni aspettativa. \u00c8 quella che oggi trovi nella nostra <a href=\"https:\/\/kingsbox.com\/it-it\/product\/kingsbox-svr-elite-lifting-platform\">SVR Elite Platform<\/a>: un concentrato di resistenza, stabilit\u00e0 e affidabilit\u00e0 che soddisfa anche gli atleti pi\u00f9 esigenti.<\/p>\n<p>Concentrandoci su questi aspetti, le pedane SVR assicurano prestazioni eccellenti e lunga durata in ogni disciplina: dal weightlifting al powerlifting fino al sollevamento olimpico. Una scelta strategica per chi pretende il massimo, in palestra o in gara.<\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-306683 alignnone\" src=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/SVR-Platform-Close-Up-800x450.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/SVR-Platform-Close-Up-800x450.png 800w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/SVR-Platform-Close-Up-768x432.png 768w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/SVR-Platform-Close-Up.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Differenze_tra_le_piattaforme_KingsBox_SVR_e_SVR_Elite\"><\/span><strong>Differenze tra le piattaforme KingsBox SVR e SVR Elite<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<table style=\"border-collapse: collapse;width: 100%;height: 505px\">\n<tbody>\n<tr style=\"height: 66px\">\n<td style=\"width: 33.3333%;height: 66px\"><\/td>\n<td style=\"width: 33.3333%;height: 66px\">\n<h4><strong><a href=\"https:\/\/kingsbox.com\/it-it\/product\/kingsbox-svr-elite-lifting-platform\">SVR Elite Platform<\/a> \u2013 Massime prestazioni<\/strong><\/h4>\n<\/td>\n<td style=\"width: 33.3333%;height: 66px\">\n<h4><strong><a href=\"https:\/\/kingsbox.com\/it-it\/product\/kingsbox-svr-standard-lifting-platform\">SVR Platform<\/a> \u2013 Miglior rapporto qualit\u00e0\/prezzo<\/strong><\/h4>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"width: 33.3333%;height: 24px\"><strong>Strati:<\/strong><\/td>\n<td style=\"width: 33.3333%;height: 24px\">3 strati (mattonelle in gomma speciale + 2 strati di schiuma SVR)<\/td>\n<td style=\"width: 33.3333%;height: 24px\">2 strati (mattonelle in gomma speciale + 1 strato di schiuma SVR)<\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"width: 33.3333%;height: 24px\"><strong>Legno:<\/strong><\/td>\n<td style=\"width: 33.3333%;height: 24px\">Compensato multistrato da 50 mm con finitura in rovere e logo KingsBox inciso<\/td>\n<td style=\"width: 33.3333%;height: 24px\">Compensato in betulla da 30 mm con logo KingsBox inciso<\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"width: 33.3333%;height: 24px\"><strong>Telaio:<\/strong><\/td>\n<td style=\"width: 33.3333%;height: 24px\">Acciaio verniciato a polvere<\/td>\n<td style=\"width: 33.3333%;height: 24px\">Acciaio verniciato a polvere<\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"width: 33.3333%;height: 24px\"><strong>Assorbimento delle vibrazioni:<\/strong><\/td>\n<td style=\"width: 33.3333%;height: 24px\">Fino <strong>al 200%<\/strong> in pi\u00f9 di assorbimento rispetto a piastrelle standard da 30 mm<em> (in base al tipo di pavimento sottostante)<br \/>\n<\/em><\/td>\n<td style=\"width: 33.3333%;height: 24px\">Fino al <strong>130% pi\u00f9 efficace<\/strong> rispetto alle classiche mattonelle in gomma da 30 mm <em>(in base al tipo di pavimento sottostante<\/em><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"width: 33.3333%;height: 24px\"><strong>Caratteristiche aggiuntive:<\/strong><\/td>\n<td style=\"width: 33.3333%;height: 24px\">Linea centrale per il posizionamento, personalizzazione completa, disponibile in versione standard oppure integrata a rack<\/td>\n<td style=\"width: 33.3333%;height: 24px\"><strong>Caratteristiche extra<\/strong> personalizzazione completa, disponibile in versione standard oppure integrata a rack<\/td>\n<\/tr>\n<tr style=\"height: 319px\">\n<td style=\"width: 33.3333%;height: 319px\"><strong>\u00a0<\/strong><\/td>\n<td style=\"width: 33.3333%;height: 319px\"><img decoding=\"async\" class=\"alignnone size-full wp-image-306671\" src=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/KingsBox-SVR-Elite-Lifting-Platform-Structure.png\" alt=\"\" width=\"591\" height=\"413\" \/><\/td>\n<td style=\"width: 33.3333%;height: 319px\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-306677\" src=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/KingsBox-SVR-Standard-Lifting-Platform-Structure.png\" alt=\"\" width=\"591\" height=\"413\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2><span class=\"ez-toc-section\" id=\"Perche_una_palestra_ha_bisogno_di_una_pedana\"><\/span><strong>Perch\u00e9 una palestra ha bisogno di una pedana?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ci sono diversi motivi per cui una palestra dovrebbe dotarsi di una pedana per il sollevamento pesi, tra cui:<\/p>\n<ul>\n<li><strong>Protezione del pavimento:<\/strong> i pesi lasciati cadere possono rovinare il pavimento, causando danni costosi da riparare. Una pedana funge da ammortizzatore, preservando l\u2019integrit\u00e0 del pavimento.<\/li>\n<li><strong>Protezione di dischi e bilancieri:<\/strong> i dischi bumper e i bilancieri rappresentano investimenti importanti per qualsiasi palestra. Una pedana di qualit\u00e0 aiuta a prevenire danni, prolungando la durata dell\u2019attrezzatura.<\/li>\n<li><strong>Delimitare chiaramente l\u2019area di sollevamento:<\/strong> una pedana dedicata identifica in modo chiaro lo spazio riservato al sollevamento pesi, aumentando la sicurezza<\/li>\n<li><strong>Ridurre il rimbalzo del bilanciere:<\/strong> Un bilanciere che rimbalza troppo pu\u00f2 diventare imprevedibile e rischioso. Le pedane ammortizzanti attutiscono l\u2019impatto, limitano il rimbalzo e rendono ogni sollevamento pi\u00f9 controllato e sicuro.<\/li>\n<li><strong>Limitare rumori e vibrazioni:<\/strong> uno dei vantaggi principali \u00e8 la riduzione significativa di rumori e vibrazioni, un aspetto fondamentale negli edifici condivisi, dove \u00e8 importante non disturbare i vicini.<\/li>\n<li><strong>Riduzione acustica e anti-vibrazione &#8211; <\/strong>Uno dei vantaggi principali \u00e8 la riduzione di rumori e vibrazioni, perfetta anche per palestre situate in condomini o strutture multiuso.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Quale_pedana_da_sollevamento_scegliere_per_la_tua_palestra\"><\/span><strong>Quale pedana da sollevamento scegliere per la tua palestra?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le pedane SVR sono ideali per le palestre professionali, in particolare quelle inserite in edifici polifunzionali con uffici o negozi adiacenti. La loro capacit\u00e0 di isolare vibrazioni e suoni rende l\u2019allenamento pi\u00f9 sicuro per l\u2019atleta e pi\u00f9 tollerabile per l\u2019ambiente circostante.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-306698 alignnone\" src=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/Black-Box-Platform-800x450.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/Black-Box-Platform-800x450.png 800w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/Black-Box-Platform-768x432.png 768w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2025\/06\/Black-Box-Platform.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>A differenza della maggior parte delle pedane \u2013 spesso realizzate con un solo strato di mattonelle in gomma \u2013 le pedane SVR sono composte da 2 strati (versione standard) o 3 strati (versione Elite) di materiali ammortizzanti ad alta prestazione. I test eseguiti dimostrano un\u2019efficace riduzione di vibrazioni e rumori, oltre a un\u2019elevata protezione per il pavimento, anche in ambienti con esigenze acustiche particolari.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Pronto_a_rivoluzionare_lesperienza_di_sollevamento_nella_tua_palestra\"><\/span><strong>Pronto a rivoluzionare l\u2019esperienza di sollevamento nella tua palestra?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Investire in una pedana da sollevamento di alta qualit\u00e0 come la <a href=\"https:\/\/kingsbox.com\/it-it\/product\/kingsbox-svr-standard-lifting-platform\">KingsBox SVR<\/a> o <a href=\"https:\/\/kingsbox.com\/it-it\/product\/kingsbox-svr-elite-lifting-platform\">SVR Elite<\/a>, pu\u00f2 trasformare completamente l\u2019ambiente della tua palestra. Queste pedane riducono rumori e vibrazioni, proteggono attrezzature e pavimenti e creano uno spazio di lavoro sicuro e ben definito.<\/p>\n<p>Che tu stia allestendo una palestra professionale in un edificio condiviso o desideri migliorare il tuo home gym, le pedane SVR rappresentano la soluzione ideale per chi prende l\u2019allenamento sul serio.<\/p>\n<p>Prova la differenza oggi stesso e offri ai tuoi iscritti il miglior ambiente di allenamento possibile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una delle sfide principali per molti gestori di palestre \u00e8 quella di trovare una soluzione efficace per il sollevamento pesi, soprattutto quando si tratta di ridurre rumori e vibrazioni durante gli allenamenti. \u00c8 proprio da questa esigenza concreta che nasce la nostra idea: una soluzione semplice ma ingegnosa, pensata per abbattere il rumore, proteggere il [&hellip;]<\/p>\n","protected":false},"author":14796,"featured_media":306717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93,5323,5407],"tags":[],"class_list":["post-306728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-come-scegliere","category-innovation","category-prodotti"],"_links":{"self":[{"href":"https:\/\/kingsbox.com\/blog\/wp-json\/wp\/v2\/posts\/306728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kingsbox.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kingsbox.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kingsbox.com\/blog\/wp-json\/wp\/v2\/users\/14796"}],"replies":[{"embeddable":true,"href":"https:\/\/kingsbox.com\/blog\/wp-json\/wp\/v2\/comments?post=306728"}],"version-history":[{"count":3,"href":"https:\/\/kingsbox.com\/blog\/wp-json\/wp\/v2\/posts\/306728\/revisions"}],"predecessor-version":[{"id":306742,"href":"https:\/\/kingsbox.com\/blog\/wp-json\/wp\/v2\/posts\/306728\/revisions\/306742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kingsbox.com\/blog\/wp-json\/wp\/v2\/media\/306717"}],"wp:attachment":[{"href":"https:\/\/kingsbox.com\/blog\/wp-json\/wp\/v2\/media?parent=306728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kingsbox.com\/blog\/wp-json\/wp\/v2\/categories?post=306728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kingsbox.com\/blog\/wp-json\/wp\/v2\/tags?post=306728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}