{"id":299039,"date":"2023-02-13T12:25:59","date_gmt":"2023-02-13T11:25:59","guid":{"rendered":"https:\/\/kingsbox.com\/blog\/?p=299039"},"modified":"2023-02-13T12:25:59","modified_gmt":"2023-02-13T11:25:59","slug":"comment-gerons-nous-les-changements-reguliers-dans-la-chaine-dapprovisionnement-i-apercu-de-notre-responsable-de-la-chaine-dapprovisionnement","status":"publish","type":"post","link":"https:\/\/kingsbox.com\/blog\/fr\/home-gym-fr\/comment-gerons-nous-les-changements-reguliers-dans-la-chaine-dapprovisionnement-i-apercu-de-notre-responsable-de-la-chaine-dapprovisionnement\/","title":{"rendered":"Comment g\u00e9rons-nous les changements r\u00e9guliers dans la cha\u00eene d&rsquo;approvisionnement I Aper\u00e7u de notre responsable de la cha\u00eene d&rsquo;approvisionnement"},"content":{"rendered":"<p>La cha\u00eene d&rsquo;approvisionnement KingsBox est le r\u00e9seau d&rsquo;organisations, de personnes, d&rsquo;activit\u00e9s, d&rsquo;informations et de ressources appliqu\u00e9es dans la cr\u00e9ation et la livraison d&rsquo;un produit. Il comprend toutes les activit\u00e9s li\u00e9es \u00e0 l&rsquo;approvisionnement en mat\u00e9riaux, \u00e0 la fabrication et \u00e0 l&rsquo;assemblage, \u00e0 l&rsquo;entreposage et \u00e0 la distribution, ainsi qu&rsquo;\u00e0 la livraison du produit final aux clients.<\/p>\n<p>La cha\u00eene d&rsquo;approvisionnement commence par l&rsquo;approvisionnement des mat\u00e9riaux, puis le processus de transformation de ces mat\u00e9riaux en produit final, et ensuite la livraison de ce produit au client. En cours de tout cela, de nombreux acteurs diff\u00e9rents sont impliqu\u00e9s, tels que les fournisseurs, les fabricants, les distributeurs, les fournisseurs de logistique, etc.<\/p>\n<p>Une gestion efficace de la cha\u00eene d&rsquo;approvisionnement implique la coordination et l&rsquo;int\u00e9gration de ces activit\u00e9s afin de minimiser les co\u00fbts et d&rsquo;optimiser la performance globale de la cha\u00eene d&rsquo;approvisionnement. Cela inclut des activit\u00e9s telles que la pr\u00e9vision de la demande, la gestion des stocks et la planification logistique, ainsi que la gestion des relations avec les fournisseurs.<\/p>\n<p><strong>Au cours des derni\u00e8res ann\u00e9es, la gestion de la cha\u00eene d&rsquo;approvisionnement est devenue de plus en plus importante en tant que d\u00e9partement KingsBox.<\/strong> En outre, la concurrence mondiale s&rsquo;est intensifi\u00e9e et le rythme des affaires s&rsquo;est acc\u00e9l\u00e9r\u00e9. Nous sommes toujours sous pression pour livrer des produits de meilleure qualit\u00e9 plus rapidement et moins cher, ce qui n\u00e9cessite une gestion efficace et efficiente de la cha\u00eene d&rsquo;approvisionnement.<\/p>\n<p>Jetons un coup d&rsquo;\u0153il \u00e0 sa fa\u00e7on d&rsquo;organiser la cha\u00eene d&rsquo;approvisionnement chez KingsBox, pour recevoir tout l&rsquo;\u00e9quipement \u00e0 temps et le livrer avec succ\u00e8s \u00e0 nos clients.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_74 counter-hierarchy ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Indice dei contenuti<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04347be52a6\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04347be52a6\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/kingsbox.com\/blog\/fr\/home-gym-fr\/comment-gerons-nous-les-changements-reguliers-dans-la-chaine-dapprovisionnement-i-apercu-de-notre-responsable-de-la-chaine-dapprovisionnement\/#Trois_branches_de_la_chaine_dapprovisionnement_KingsBox\" >Trois branches de la cha\u00eene d&rsquo;approvisionnement KingsBox<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/kingsbox.com\/blog\/fr\/home-gym-fr\/comment-gerons-nous-les-changements-reguliers-dans-la-chaine-dapprovisionnement-i-apercu-de-notre-responsable-de-la-chaine-dapprovisionnement\/#KingsBox_et_la_chaine_dapprovisionnement_mondiale_pendant_la_pandemie\" >KingsBox et la cha\u00eene d&rsquo;approvisionnement mondiale pendant la pand\u00e9mie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/kingsbox.com\/blog\/fr\/home-gym-fr\/comment-gerons-nous-les-changements-reguliers-dans-la-chaine-dapprovisionnement-i-apercu-de-notre-responsable-de-la-chaine-dapprovisionnement\/#Mode_dexpedition_LCL_pendant_la_pandemie\" >Mode d&rsquo;exp\u00e9dition LCL pendant la pand\u00e9mie.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/kingsbox.com\/blog\/fr\/home-gym-fr\/comment-gerons-nous-les-changements-reguliers-dans-la-chaine-dapprovisionnement-i-apercu-de-notre-responsable-de-la-chaine-dapprovisionnement\/#Plus_de_collaborations_avec_les_fournisseurs_locaux_et_dautres_fournisseurs_de_lUE\" >Plus de collaborations avec les fournisseurs locaux et d&rsquo;autres fournisseurs de l&rsquo;UE<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Trois_branches_de_la_chaine_dapprovisionnement_KingsBox\"><\/span><strong>Trois branches de la cha\u00eene d&rsquo;approvisionnement KingsBox<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><strong>Service des achats \u2013 \u00e9quipe qui ach\u00e8te les bons produits<\/strong><\/h3>\n<p>Le service des achats est un domaine fonctionnel au sein d&rsquo;une entreprise qui est responsable de l&rsquo;acquisition des biens et services n\u00e9cessaires pour les op\u00e9rations de l&rsquo;organisation. Le r\u00f4le principal du service des achats est d&rsquo;acheter les bons produits, au bon moment, de bonne quantit\u00e9 et au bon prix.<\/p>\n<p>Le service des achats de KingsBox est responsable d&rsquo;une vari\u00e9t\u00e9 de t\u00e2ches, y compris\u00a0:<\/p>\n<ul>\n<li>L&rsquo;identification des besoins de l&rsquo;entreprise<\/li>\n<li>L&rsquo;identification des fournisseurs potentiels<\/li>\n<li>N\u00e9gociations avec les fournisseurs au sujet du prix et sur les conditions<\/li>\n<li>Cr\u00e9ation et gestion des bons de commande<\/li>\n<li>Coordination de la logistique et du transport pour assurer la livraison des marchandises en temps opportun<\/li>\n<li>Gestion des niveaux des stocks et suivi des bons de commande<\/li>\n<li>Les relations avec les fournisseurs<\/li>\n<li>R\u00e9solutions des probl\u00e8mes li\u00e9s \u00e0 la qualit\u00e9 ou \u00e0 la livraison des marchandises<\/li>\n<\/ul>\n<p>Nous travaillons en \u00e9troite collaboration avec d&rsquo;autres d\u00e9partements tels que la production, la logistique et les finances pour nous assurer que les besoins d&rsquo;achat de l&rsquo;entreprise sont satisfaits de mani\u00e8re rapide et efficace.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-298983\" src=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/marko-pockar-portret_blog_2022-1-800x534.jpg\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/marko-pockar-portret_blog_2022-1-800x534.jpg 800w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/marko-pockar-portret_blog_2022-1-768x512.jpg 768w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/marko-pockar-portret_blog_2022-1-1536x1024.jpg 1536w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/marko-pockar-portret_blog_2022-1.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3><strong>Service logistique KingsBox \u2013 s&rsquo;assurer que les produits sont livr\u00e9s \u00e0 temps<\/strong><strong> et au bon endroit<\/strong><\/h3>\n<p>Le service logistique KingsBox fait r\u00e9f\u00e9rence \u00e0 la coordination et \u00e0 la gestion du mouvement des marchandises et des mat\u00e9riaux. Cela comprend la planification, la mise en \u0153uvre et le contr\u00f4le du flux des mat\u00e9riaux efficace et rentable, des stocks en cours de fabrication et des produits finis du point d&rsquo;origine au client.<\/p>\n<p>L&rsquo;objectif principal est de s&rsquo;assurer que les bons produits sont livr\u00e9s au bon endroit, au bon moment et dans un bon \u00e9tat. Cela peut impliquer une vari\u00e9t\u00e9 de t\u00e2ches comme\u00a0:<\/p>\n<ul>\n<li>Transport de marchandises des fournisseurs vers les entrep\u00f4ts ou les usines de fabrication<\/li>\n<li>Stockage et gestion des niveaux de stocks<\/li>\n<li>Planification des livraisons aux clients<\/li>\n<li>Coordination avec les entreprises de transport ou les fournisseurs de logistique<\/li>\n<li>Gestion du retour et de l&rsquo;\u00e9limination des marchandises<\/li>\n<li>Gestion du flux de marchandises tout au long de la cha\u00eene d&rsquo;approvisionnement<\/li>\n<li>Gestion du suivi et de la documentation des marchandises en route<\/li>\n<\/ul>\n<p>KingsBox dispose d&rsquo;un service logistique efficace, qui contribue \u00e0 l&rsquo;efficacit\u00e9, \u00e0 la r\u00e9duction des co\u00fbts et \u00e0 l&rsquo;am\u00e9lioration de la satisfaction de la client\u00e8le.<\/p>\n<h3><strong>Entrep\u00f4t KingsBox \u2013 stockage et pr\u00e9paration de l&rsquo;\u00e9quipement pour la livraison<\/strong><\/h3>\n<p>L&rsquo;entrep\u00f4t KingsBox est utilis\u00e9 pour stocker et g\u00e9rer les mat\u00e9riaux, l&rsquo;\u00e9quipement, les produits et les travaux d&#8217;emballage. Nous stockons des mat\u00e9riaux tels que le carton, des pi\u00e8ces en plastique, des pi\u00e8ces en acier et tout l&rsquo;\u00e9quipement achet\u00e9 ou produit.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-299016\" src=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-21-800x534.png\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-21-800x534.png 800w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-21-768x512.png 768w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-21-1536x1024.png 1536w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-21.png 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Nous stockons \u00e9galement des articles tels que des produits emball\u00e9s, pr\u00eats \u00e0 \u00eatre distribu\u00e9s et livr\u00e9s aux clients. L&rsquo;entrep\u00f4t KingsBox comprend des zones sp\u00e9cifiques pour l&rsquo;assemblage des emballages, le contr\u00f4le de la qualit\u00e9 et la gestion des stocks.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-299006\" src=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-22-800x534.png\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-22-800x534.png 800w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-22-768x512.png 768w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-22-1536x1024.png 1536w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-22.png 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Nous disposons de quais de chargement ou d&rsquo;autres moyens de r\u00e9ception et d&rsquo;exp\u00e9dition des mat\u00e9riaux et des produits, ainsi que d&rsquo;\u00e9quipement de manutention des mat\u00e9riaux tels que des \u00e9l\u00e9vateurs et des transpalettes pour d\u00e9placer les mat\u00e9riaux autour de l&rsquo;installation.<\/p>\n<p>Dans les entrep\u00f4ts KingsBox, les technologies modernes et l&rsquo;automatisation sont utilis\u00e9es pour am\u00e9liorer l&rsquo;efficacit\u00e9, la pr\u00e9cision et la tra\u00e7abilit\u00e9, telles que les codes \u00e0 barres et les logiciels de gestion d&rsquo;entrep\u00f4t.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-299026\" src=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-20-800x534.png\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-20-800x534.png 800w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-20-768x512.png 768w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-20-1536x1024.png 1536w, https:\/\/kingsbox.com\/blog\/wp-content\/uploads\/2023\/02\/Izdelek-brez-naslova-20.png 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"KingsBox_et_la_chaine_dapprovisionnement_mondiale_pendant_la_pandemie\"><\/span><strong>KingsBox et la cha\u00eene d&rsquo;approvisionnement mondiale pendant la pand\u00e9mie<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La pand\u00e9mie de COVID-19 a caus\u00e9 d&rsquo;importantes perturbations dans l&rsquo;industrie du transport maritime. Voici quelques-uns des principaux probl\u00e8mes qui sont apparus\u00a0:<\/p>\n<ul>\n<li><strong>Congestion portuaire\u00a0:<\/strong> de nombreux ports \u00e0 travers le monde ont connu de graves embouteillages en raison d&rsquo;une capacit\u00e9 r\u00e9duite \u00e0 cause de mesures de distanciation sociale, d&rsquo;une demande accrue de marchandises et d&rsquo;une p\u00e9nurie de conteneurs de fret disponibles. Cela a entra\u00een\u00e9 des retards dans le chargement et le d\u00e9chargement des navires et des d\u00e9lais accrus pour la cargaison.<\/li>\n<li><strong>P\u00e9nuries d&rsquo;\u00e9quipement\u00a0:<\/strong> La pand\u00e9mie a entra\u00een\u00e9 une p\u00e9nurie de conteneurs maritimes, de nombreux conteneurs \u00e9tant bloqu\u00e9s dans les ports ou d\u00e9tenus \u00e0 leur origine par des fournisseurs. Cela a cr\u00e9\u00e9 un goulot d&rsquo;\u00e9tranglement dans la cha\u00eene d&rsquo;approvisionnement et augment\u00e9 les co\u00fbts pour les exp\u00e9diteurs.<\/li>\n<\/ul>\n<p>La pand\u00e9mie a provoqu\u00e9 une perturbation g\u00e9n\u00e9ralis\u00e9e des cha\u00eenes d&rsquo;approvisionnement mondiales, de nombreuses usines ferm\u00e9es ou fonctionnant \u00e0 capacit\u00e9 r\u00e9duite. Cela s&rsquo;est exprim\u00e9 par un ralentissement de la production et un d\u00e9s\u00e9quilibre de la demande et de l&rsquo;offre de marchandises, ce qui a entra\u00een\u00e9 une augmentation des taux de fret et des difficult\u00e9s \u00e0 s\u00e9curiser l&rsquo;espace maritime.<\/p>\n<p>De nombreuses compagnies maritimes ont r\u00e9duit le nombre de travers\u00e9es pour g\u00e9rer l&rsquo;impact de la pand\u00e9mie, ce qui a entra\u00een\u00e9 une r\u00e9duction de la capacit\u00e9 et une concurrence accrue pour l&rsquo;espace maritime.<\/p>\n<p>\u00c0 cause de la congestion des ports et des p\u00e9nuries d&rsquo;\u00e9quipement, les marchandises \u00e9taient souvent retenues dans les ports ou les terminaux pendant des p\u00e9riodes prolong\u00e9es, ce qui entra\u00eene une augmentation des surestaries et des frais suppl\u00e9mentaires pour les exp\u00e9diteurs.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Mode_dexpedition_LCL_pendant_la_pandemie\"><\/span><strong>Mode d&rsquo;exp\u00e9dition LCL pendant la pand\u00e9mie.<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>LCL (Less than Container Load) est une m\u00e9thode d&rsquo;exp\u00e9dition o\u00f9 plusieurs petites exp\u00e9ditions de diff\u00e9rents clients sont consolid\u00e9es dans un seul conteneur. Cela contraste avec l&rsquo;exp\u00e9dition FCL (Full Container Load), o\u00f9 un seul client loue un conteneur entier.<\/p>\n<p>L&rsquo;exp\u00e9dition LCL a <span style=\"color: #99cc00\">plusieurs avantages<\/span>, tels que\u00a0:<\/p>\n<ul>\n<li><strong>Co\u00fbts r\u00e9duits\u00a0:<\/strong> l&rsquo;exp\u00e9dition LCL co\u00fbte g\u00e9n\u00e9ralement moins cher que l&rsquo;exp\u00e9dition FCL, car les co\u00fbts du conteneur et du transport sont partag\u00e9s entre plusieurs clients.<\/li>\n<li><strong>Flexibilit\u00e9 accrue\u00a0:<\/strong> l&rsquo;exp\u00e9dition LCL permet aux entreprises d&rsquo;exp\u00e9dier de plus petites quantit\u00e9s de marchandises, ce qui le rend plus adapt\u00e9 aux entreprises ayant des volumes plus bas ou des besoins d&rsquo;exp\u00e9dition moins fr\u00e9quents.<\/li>\n<li><strong>Acc\u00e8s \u00e0 de nouveaux march\u00e9s\u00a0:<\/strong> l&rsquo;exp\u00e9dition LCL peut permettre aux entreprises d&rsquo;acc\u00e9der \u00e0 de nouveaux march\u00e9s qui seraient trop co\u00fbteux avec l&rsquo;exp\u00e9dition FCL.<\/li>\n<\/ul>\n<p>Cependant, l&rsquo;exp\u00e9dition LCL a aussi des <span style=\"color: #ff0000\">inconv\u00e9nients potentiels<\/span>\u00a0:<\/p>\n<ul>\n<li><strong>Augmentation des d\u00e9lais\u00a0:<\/strong> les exp\u00e9ditions LCL peuvent prendre plus de temps pour atteindre leur destination, car le travail de la cargaison dans les ports prend potentiellement plus de temps.<\/li>\n<li><strong>Risque accru de dommages\u00a0:<\/strong> les exp\u00e9ditions LCL pr\u00e9sentent potentiellement un risque plus \u00e9lev\u00e9 de dommages parce que la cargaison est faite avec d&rsquo;autres exp\u00e9ditions.<\/li>\n<li><strong>Contr\u00f4le limit\u00e9 sur le temps de livraison\u00a0:<\/strong> avec l&rsquo;exp\u00e9dition LCL, les entreprises peuvent avoir moins de contr\u00f4le sur le temps de livraison, car le calendrier d&rsquo;exp\u00e9dition est d\u00e9termin\u00e9 par la ligne d&rsquo;exp\u00e9dition.<\/li>\n<\/ul>\n<p>Dans l&rsquo;ensemble, l&rsquo;exp\u00e9dition LCL \u00e9tait une option rentable et flexible pour les entreprises ayant des besoins d&rsquo;exp\u00e9dition plus faibles ou moins fr\u00e9quents. Cependant, il est important de penser aux avantages et aux inconv\u00e9nients et de comprendre les impacts potentiels sur les d\u00e9lais, les calendriers de livraison et la manutention du fret avant de passer de FCL \u00e0 LCL.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Plus_de_collaborations_avec_les_fournisseurs_locaux_et_dautres_fournisseurs_de_lUE\"><\/span><strong>Plus de collaborations avec les fournisseurs locaux et d&rsquo;autres fournisseurs de l&rsquo;UE<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Pendant la pand\u00e9mie, ce mode de coop\u00e9ration s&rsquo;est av\u00e9r\u00e9 \u00eatre une bonne alternative pour KingsBox, gr\u00e2ce \u00e0 ces avantages\u00a0:<\/p>\n<ul>\n<li><strong>D\u00e9lais de livraison r\u00e9duits<\/strong><\/li>\n<\/ul>\n<p>Les fournisseurs locaux \u00e9taient souvent en mesure de livrer les marchandises plus rapidement que les fournisseurs situ\u00e9s plus loin, car ils \u00e9taient plus proches des installations de fabrication ou de distribution de l&rsquo;entreprise. C&rsquo;\u00e9tait tr\u00e8s important pour r\u00e9duire les d\u00e9lais et augmenter l&rsquo;efficacit\u00e9.<\/p>\n<ul>\n<li><strong>Communication am\u00e9lior\u00e9e<\/strong><\/li>\n<\/ul>\n<p>Travailler avec des fournisseurs locaux s&rsquo;est av\u00e9r\u00e9 plus facile, gr\u00e2ce \u00e0 la communication et la coordination. Ce qui a aid\u00e9 \u00e0 r\u00e9duire le risque d&rsquo;erreurs ou de malentendus. Cela a \u00e9galement contribu\u00e9 \u00e0 am\u00e9liorer la qualit\u00e9 globale des biens fournis.<\/p>\n<ul>\n<li><strong>R\u00e9duction des co\u00fbts de transport<\/strong><\/li>\n<\/ul>\n<p>Le travail avec des fournisseurs locaux a contribu\u00e9 \u00e0 r\u00e9duire les co\u00fbts de transport, car les marchandises n&rsquo;avaient pas \u00e0 aller aussi loin pour atteindre les installations de l&rsquo;entreprise. Cela a permis de r\u00e9duire les co\u00fbts g\u00e9n\u00e9raux et d&rsquo;augmenter la rentabilit\u00e9.<\/p>\n<ul>\n<li><strong>Un soutien de l&rsquo;\u00e9conomie locale<\/strong><\/li>\n<\/ul>\n<p>En travaillant avec les fournisseurs locaux, l&rsquo;entreprise a contribu\u00e9 \u00e0 soutenir l&rsquo;\u00e9conomie locale, ce qui a \u00e9t\u00e9 b\u00e9n\u00e9fique pour la communaut\u00e9 et la r\u00e9putation de l&rsquo;entreprise.<\/p>\n<ul>\n<li><strong>R\u00e9action rapide aux changements de la demande<\/strong><\/li>\n<\/ul>\n<p>Les fournisseurs locaux peuvent rapidement r\u00e9agir aux changements de la demande, car ils sont plus proches de l&rsquo;entreprise et peuvent effectuer des ajustements plus rapidement.<\/p>\n<ul>\n<li><strong>Un meilleur contr\u00f4le de la cha\u00eene d&rsquo;approvisionnement<\/strong><\/li>\n<\/ul>\n<p>Un plus grand contr\u00f4le sur sa cha\u00eene d&rsquo;approvisionnement est possible gr\u00e2ce aux fournisseurs locaux, ce qui nous permet de surveiller et de g\u00e9rer le processus de production de plus pr\u00e8s.<\/p>\n<ul>\n<li><strong>Une plus grande r\u00e9silience aux perturbations<\/strong><\/li>\n<\/ul>\n<p>L&rsquo;utilisation de fournisseurs locaux a permis d&rsquo;att\u00e9nuer l&rsquo;impact des perturbations de la cha\u00eene d&rsquo;approvisionnement caus\u00e9es par des facteurs tels que les catastrophes naturelles, le navire Evergreen bloquant tout le trafic dans le canal de Suez, les fermetures de ports ou les pand\u00e9mies, car ils sont moins susceptibles d&rsquo;\u00eatre affect\u00e9s par ces \u00e9v\u00e9nements.<\/p>\n<p>Il est important de noter que dans certains cas, il est impossible d&rsquo;utiliser uniquement les services des fournisseurs locaux. Cependant, la collaboration avec les fournisseurs locaux dans la mesure du possible a procur\u00e9 de nombreux avantages \u00e0 KingsBox et \u00e0 la communaut\u00e9 locale.<\/p>\n<p>Comme vous pouvez le voir, la cha\u00eene d&rsquo;approvisionnement est un sujet tr\u00e8s int\u00e9ressant et vari\u00e9. L&rsquo;une de nos principales priorit\u00e9s est de nous am\u00e9liorer dans ce domaine, car il est tr\u00e8s important de produire et de fournir des \u00e9quipements de qualit\u00e9 \u00e0 temps. Notre \u00e9quipe est confront\u00e9e quotidiennement \u00e0 diff\u00e9rents d\u00e9fis et cherche toujours des moyens de s&rsquo;am\u00e9liorer et de n\u00e9gocier, de rendre nos clients plus heureux et de d\u00e9passer leurs attentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cha\u00eene d&rsquo;approvisionnement KingsBox est le r\u00e9seau d&rsquo;organisations, de personnes, d&rsquo;activit\u00e9s, d&rsquo;informations et de ressources appliqu\u00e9es dans la cr\u00e9ation et la livraison d&rsquo;un produit. Il comprend toutes les activit\u00e9s li\u00e9es \u00e0 l&rsquo;approvisionnement en mat\u00e9riaux, \u00e0 la fabrication et \u00e0 l&rsquo;assemblage, \u00e0 l&rsquo;entreposage et \u00e0 la distribution, ainsi qu&rsquo;\u00e0 la livraison du produit final aux clients. [&hellip;]<\/p>\n","protected":false},"author":14796,"featured_media":298997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5424],"tags":[],"class_list":["post-299039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home-gym-fr"],"_links":{"self":[{"href":"https:\/\/kingsbox.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/299039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kingsbox.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kingsbox.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kingsbox.com\/blog\/fr\/wp-json\/wp\/v2\/users\/14796"}],"replies":[{"embeddable":true,"href":"https:\/\/kingsbox.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=299039"}],"version-history":[{"count":1,"href":"https:\/\/kingsbox.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/299039\/revisions"}],"predecessor-version":[{"id":299040,"href":"https:\/\/kingsbox.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/299039\/revisions\/299040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kingsbox.com\/blog\/fr\/wp-json\/wp\/v2\/media\/298997"}],"wp:attachment":[{"href":"https:\/\/kingsbox.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=299039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kingsbox.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=299039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kingsbox.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=299039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}